{"id":59,"date":"2024-01-03T13:19:20","date_gmt":"2024-01-03T13:19:20","guid":{"rendered":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/members\/"},"modified":"2024-01-03T13:19:20","modified_gmt":"2024-01-03T13:19:20","slug":"members","status":"publish","type":"page","link":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/members\/","title":{"rendered":"Members"},"content":{"rendered":"<p>[ultimatemember form_id=&#8221;54&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ultimatemember form_id=&#8221;54&#8243;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/wp-json\/wp\/v2\/pages\/59"}],"collection":[{"href":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/wp-json\/wp\/v2\/comments?post=59"}],"version-history":[{"count":0,"href":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/wp-json\/wp\/v2\/pages\/59\/revisions"}],"wp:attachment":[{"href":"https:\/\/myaccount.prettifaceboutique.com\/index.php\/wp-json\/wp\/v2\/media?parent=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}